{"id":164,"count":1,"description":"","link":"https:\/\/stoneedge.com\/kb\/tags\/setup\/","name":"Setup","slug":"setup","taxonomy":"ht_kb_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Setup Archives - Stone Edge Order Manager<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stoneedge.com\/kb\/tags\/setup\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Setup Archives - Stone Edge Order Manager\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stoneedge.com\/kb\/tags\/setup\/\" \/>\n<meta property=\"og:site_name\" content=\"Stone Edge Order Manager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/tags\\\/setup\\\/\",\"url\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/tags\\\/setup\\\/\",\"name\":\"Setup Archives - Stone Edge Order Manager\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/tags\\\/setup\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/tags\\\/setup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Setup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/#website\",\"url\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/\",\"name\":\"Stone Edge Order Manager\",\"description\":\"Documentation for the Stone Edge Order Manager\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stoneedge.com\\\/kb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Setup Archives - Stone Edge Order Manager","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stoneedge.com\/kb\/tags\/setup\/","og_locale":"en_US","og_type":"article","og_title":"Setup Archives - Stone Edge Order Manager","og_url":"https:\/\/stoneedge.com\/kb\/tags\/setup\/","og_site_name":"Stone Edge Order Manager","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/stoneedge.com\/kb\/tags\/setup\/","url":"https:\/\/stoneedge.com\/kb\/tags\/setup\/","name":"Setup Archives - Stone Edge Order Manager","isPartOf":{"@id":"https:\/\/stoneedge.com\/kb\/#website"},"breadcrumb":{"@id":"https:\/\/stoneedge.com\/kb\/tags\/setup\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/stoneedge.com\/kb\/tags\/setup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stoneedge.com\/kb\/"},{"@type":"ListItem","position":2,"name":"Setup"}]},{"@type":"WebSite","@id":"https:\/\/stoneedge.com\/kb\/#website","url":"https:\/\/stoneedge.com\/kb\/","name":"Stone Edge Order Manager","description":"Documentation for the Stone Edge Order Manager","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stoneedge.com\/kb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/stoneedge.com\/kb\/wp-json\/wp\/v2\/ht-kb-tag\/164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoneedge.com\/kb\/wp-json\/wp\/v2\/ht-kb-tag"}],"about":[{"href":"https:\/\/stoneedge.com\/kb\/wp-json\/wp\/v2\/taxonomies\/ht_kb_tag"}],"wp:post_type":[{"href":"https:\/\/stoneedge.com\/kb\/wp-json\/wp\/v2\/ht-kb?ht-kb-tag=164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}